{"id":6951,"date":"2024-11-13T21:05:33","date_gmt":"2024-11-13T21:05:33","guid":{"rendered":"https:\/\/www.worcester.edu\/campus-life\/?page_id=6951"},"modified":"2025-11-21T16:58:57","modified_gmt":"2025-11-21T16:58:57","slug":"lgbtq-community-health-resources","status":"publish","type":"page","link":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/","title":{"rendered":"LGBTQ+ Community Health Resources"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":12043,"featured_media":0,"parent":559,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"templates\/SidebarWidth.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-6951","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGBTQ+ Community Health Resources | Worcester State University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGBTQ+ Community Health Resources | Worcester State University\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Life\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T16:58:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/lgbtq-community-health-resources\\\/\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/lgbtq-community-health-resources\\\/\",\"name\":\"LGBTQ+ Community Health Resources | Worcester State University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\"},\"datePublished\":\"2024-11-13T21:05:33+00:00\",\"dateModified\":\"2025-11-21T16:58:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/lgbtq-community-health-resources\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/lgbtq-community-health-resources\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/lgbtq-community-health-resources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Health Services\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/health-services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LGBTQ+ Community Health Resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\",\"name\":\"Campus Life\",\"description\":\"Just another Worcester State University site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGBTQ+ Community Health Resources | Worcester State University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/","og_locale":"en_US","og_type":"article","og_title":"LGBTQ+ Community Health Resources | Worcester State University","og_url":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/","og_site_name":"Campus Life","article_modified_time":"2025-11-21T16:58:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/","url":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/","name":"LGBTQ+ Community Health Resources | Worcester State University","isPartOf":{"@id":"https:\/\/www.worcester.edu\/campus-life\/#website"},"datePublished":"2024-11-13T21:05:33+00:00","dateModified":"2025-11-21T16:58:57+00:00","breadcrumb":{"@id":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.worcester.edu\/campus-life\/health-services\/lgbtq-community-health-resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worcester.edu\/campus-life\/"},{"@type":"ListItem","position":2,"name":"Health Services","item":"https:\/\/www.worcester.edu\/campus-life\/health-services\/"},{"@type":"ListItem","position":3,"name":"LGBTQ+ Community Health Resources"}]},{"@type":"WebSite","@id":"https:\/\/www.worcester.edu\/campus-life\/#website","url":"https:\/\/www.worcester.edu\/campus-life\/","name":"Campus Life","description":"Just another Worcester State University site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worcester.edu\/campus-life\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/pages\/6951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/users\/12043"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/comments?post=6951"}],"version-history":[{"count":3,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/pages\/6951\/revisions"}],"predecessor-version":[{"id":8212,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/pages\/6951\/revisions\/8212"}],"up":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/pages\/559"}],"wp:attachment":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/media?parent=6951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}