{"id":48,"count":6,"description":"","link":"https:\/\/www.worcester.edu\/campus-life\/tag\/lgbtq\/","name":"LGBTQ+","slug":"lgbtq","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGBTQ+ Archives | Campus Life<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGBTQ+ Archives | Campus Life\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Life\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/webdev.worcester.edu\\\/campus-life\\\/tag\\\/lgbtq\\\/\",\"url\":\"https:\\\/\\\/webdev.worcester.edu\\\/campus-life\\\/tag\\\/lgbtq\\\/\",\"name\":\"LGBTQ+ Archives | Campus Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/webdev.worcester.edu\\\/campus-life\\\/tag\\\/lgbtq\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/webdev.worcester.edu\\\/campus-life\\\/tag\\\/lgbtq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LGBTQ+\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\",\"name\":\"Campus Life\",\"description\":\"Just another Worcester State University site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGBTQ+ Archives | Campus Life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/","og_locale":"en_US","og_type":"article","og_title":"LGBTQ+ Archives | Campus Life","og_url":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/","og_site_name":"Campus Life","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/","url":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/","name":"LGBTQ+ Archives | Campus Life","isPartOf":{"@id":"https:\/\/www.worcester.edu\/campus-life\/#website"},"breadcrumb":{"@id":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/webdev.worcester.edu\/campus-life\/tag\/lgbtq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worcester.edu\/campus-life\/"},{"@type":"ListItem","position":2,"name":"LGBTQ+"}]},{"@type":"WebSite","@id":"https:\/\/www.worcester.edu\/campus-life\/#website","url":"https:\/\/www.worcester.edu\/campus-life\/","name":"Campus Life","description":"Just another Worcester State University site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worcester.edu\/campus-life\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tags\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/posts?tags=48"},{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events?tags=48"},{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tec_calendar_embed?tags=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}