{"id":8976,"date":"2026-08-03T01:11:37","date_gmt":"2026-08-03T05:11:37","guid":{"rendered":"https:\/\/www.worcester.edu\/campus-life\/?post_type=tribe_events&#038;p=8976"},"modified":"2026-08-25T22:17:08","modified_gmt":"2026-08-26T02:17:08","slug":"lgbtqia-support-group","status":"publish","type":"tribe_events","link":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/","title":{"rendered":"LGBTQIA+ Support Group"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[97],"class_list":["post-8976","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-lgbtqia-community-center","cat_lgbtqia-community-center"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGBTQIA+ Support Group | Campus Life<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGBTQIA+ Support Group | Campus Life\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Life\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T02:17:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/event\\\/lgbtqia-support-group\\\/\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/event\\\/lgbtqia-support-group\\\/\",\"name\":\"LGBTQIA+ Support Group | Campus Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\"},\"datePublished\":\"2026-08-03T05:11:37+00:00\",\"dateModified\":\"2026-08-26T02:17:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/event\\\/lgbtqia-support-group\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/event\\\/lgbtqia-support-group\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/event\\\/lgbtqia-support-group\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LGBTQIA+ Support Group\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/#website\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/\",\"name\":\"Campus Life\",\"description\":\"Just another Worcester State University site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worcester.edu\\\/campus-life\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGBTQIA+ Support Group | Campus Life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/","og_locale":"en_US","og_type":"article","og_title":"LGBTQIA+ Support Group | Campus Life","og_url":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/","og_site_name":"Campus Life","article_modified_time":"2026-08-26T02:17:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/","url":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/","name":"LGBTQIA+ Support Group | Campus Life","isPartOf":{"@id":"https:\/\/www.worcester.edu\/campus-life\/#website"},"datePublished":"2026-08-03T05:11:37+00:00","dateModified":"2026-08-26T02:17:08+00:00","breadcrumb":{"@id":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.worcester.edu\/campus-life\/event\/lgbtqia-support-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worcester.edu\/campus-life\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.worcester.edu\/campus-life\/events\/"},{"@type":"ListItem","position":3,"name":"LGBTQIA+ Support Group"}]},{"@type":"WebSite","@id":"https:\/\/www.worcester.edu\/campus-life\/#website","url":"https:\/\/www.worcester.edu\/campus-life\/","name":"Campus Life","description":"Just another Worcester State University site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worcester.edu\/campus-life\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events\/8976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events\/8976\/revisions"}],"predecessor-version":[{"id":8977,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events\/8976\/revisions\/8977"}],"wp:attachment":[{"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/media?parent=8976"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tags?post=8976"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.worcester.edu\/campus-life\/wp-json\/wp\/v2\/tribe_events_cat?post=8976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}