{"id":8,"date":"2023-07-11T15:57:17","date_gmt":"2023-07-11T15:57:17","guid":{"rendered":"https:\/\/www.worcester.edu\/espanol\/?page_id=8"},"modified":"2026-05-20T15:17:07","modified_gmt":"2026-05-20T15:17:07","slug":"somos-worcester-state","status":"publish","type":"page","link":"https:\/\/www.worcester.edu\/espanol\/","title":{"rendered":"Somos Worcester State"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/FullWidth.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espa\u00f1ol - Worcester State University<\/title>\n<meta name=\"description\" content=\"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worcester.edu\/espanol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espa\u00f1ol - Worcester State University\" \/>\n<meta property=\"og:description\" content=\"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worcester.edu\/espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1ol - Worcester State University\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WorcesterStateUniversity\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T15:17:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WorcesterState\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\",\"name\":\"Espa\u00f1ol - Worcester State University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#website\"},\"datePublished\":\"2023-07-11T15:57:17+00:00\",\"dateModified\":\"2026-05-20T15:17:07+00:00\",\"description\":\"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Somos Worcester State\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\",\"name\":\"En Espa\u00f1ol - Worcester State University\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#organization\",\"name\":\"Worcester State University\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Worcester State University\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/espanol\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WorcesterStateUniversity\\\/\",\"https:\\\/\\\/x.com\\\/WorcesterState\",\"https:\\\/\\\/www.instagram.com\\\/worcesterstate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espa\u00f1ol - Worcester State University","description":"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worcester.edu\/espanol\/","og_locale":"en_US","og_type":"article","og_title":"Espa\u00f1ol - Worcester State University","og_description":"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.","og_url":"https:\/\/www.worcester.edu\/espanol\/","og_site_name":"Espa\u00f1ol - Worcester State University","article_publisher":"https:\/\/www.facebook.com\/WorcesterStateUniversity\/","article_modified_time":"2026-05-20T15:17:07+00:00","twitter_card":"summary_large_image","twitter_site":"@WorcesterState","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.worcester.edu\/espanol\/","url":"https:\/\/www.worcester.edu\/espanol\/","name":"Espa\u00f1ol - Worcester State University","isPartOf":{"@id":"https:\/\/www.worcester.edu\/espanol\/#website"},"datePublished":"2023-07-11T15:57:17+00:00","dateModified":"2026-05-20T15:17:07+00:00","description":"Formamos a nuestros estudiantes para que piensen de manera innovadora, para que se pongan manos a la obra.","breadcrumb":{"@id":"https:\/\/www.worcester.edu\/espanol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worcester.edu\/espanol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.worcester.edu\/espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worcester.edu\/espanol\/"},{"@type":"ListItem","position":2,"name":"Somos Worcester State"}]},{"@type":"WebSite","@id":"https:\/\/www.worcester.edu\/espanol\/#website","url":"https:\/\/www.worcester.edu\/espanol\/","name":"En Espa\u00f1ol - Worcester State University","description":"","publisher":{"@id":"https:\/\/www.worcester.edu\/espanol\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worcester.edu\/espanol\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.worcester.edu\/espanol\/#organization","name":"Worcester State University","url":"https:\/\/www.worcester.edu\/espanol\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.worcester.edu\/espanol\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Worcester State University"},"image":{"@id":"https:\/\/www.worcester.edu\/espanol\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WorcesterStateUniversity\/","https:\/\/x.com\/WorcesterState","https:\/\/www.instagram.com\/worcesterstate\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":4,"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":396,"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/pages\/8\/revisions\/396"}],"wp:attachment":[{"href":"https:\/\/www.worcester.edu\/espanol\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}