{"id":360,"date":"2023-08-21T17:51:58","date_gmt":"2023-08-21T17:51:58","guid":{"rendered":"https:\/\/www.worcester.edu\/international-programs\/?page_id=360"},"modified":"2023-08-21T18:06:36","modified_gmt":"2023-08-21T18:06:36","slug":"student-resources","status":"publish","type":"page","link":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/","title":{"rendered":"Student Resources"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5966,"featured_media":0,"parent":26,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"templates\/SidebarWidth.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-360","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Student Resources - International Programs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Student Resources - International Programs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/\" \/>\n<meta property=\"og:site_name\" content=\"International Programs\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T18:06:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/student-resources\\\/\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/student-resources\\\/\",\"name\":\"Student Resources - International Programs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/#website\"},\"datePublished\":\"2023-08-21T17:51:58+00:00\",\"dateModified\":\"2023-08-21T18:06:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/student-resources\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/student-resources\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/student-resources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Study Away\",\"item\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/study-away\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Student Resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/#website\",\"url\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/\",\"name\":\"International Programs\",\"description\":\"Just another Worcester State University site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worcester.edu\\\/international-programs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Student Resources - International Programs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/","og_locale":"en_US","og_type":"article","og_title":"Student Resources - International Programs","og_url":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/","og_site_name":"International Programs","article_modified_time":"2023-08-21T18:06:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/","url":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/","name":"Student Resources - International Programs","isPartOf":{"@id":"https:\/\/www.worcester.edu\/international-programs\/#website"},"datePublished":"2023-08-21T17:51:58+00:00","dateModified":"2023-08-21T18:06:36+00:00","breadcrumb":{"@id":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.worcester.edu\/international-programs\/study-away\/student-resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worcester.edu\/international-programs\/"},{"@type":"ListItem","position":2,"name":"Study Away","item":"https:\/\/www.worcester.edu\/international-programs\/study-away\/"},{"@type":"ListItem","position":3,"name":"Student Resources"}]},{"@type":"WebSite","@id":"https:\/\/www.worcester.edu\/international-programs\/#website","url":"https:\/\/www.worcester.edu\/international-programs\/","name":"International Programs","description":"Just another Worcester State University site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worcester.edu\/international-programs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/pages\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/users\/5966"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":4,"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/pages\/360\/revisions"}],"predecessor-version":[{"id":371,"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/pages\/360\/revisions\/371"}],"up":[{"embeddable":true,"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/pages\/26"}],"wp:attachment":[{"href":"https:\/\/www.worcester.edu\/international-programs\/wp-json\/wp\/v2\/media?parent=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}